{"id":2222,"count":472,"description":"","link":"https:\/\/www.nuageconceptstore.ch\/en\/categorie\/baby-clothes\/","name":"Baby","slug":"baby-clothes","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":57,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baby - Nuage<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nuageconceptstore.ch\/en\/categorie\/baby-clothes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baby - Nuage\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nuageconceptstore.ch\/en\/categorie\/baby-clothes\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/categorie\\\/baby-clothes\\\/\",\"url\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/categorie\\\/baby-clothes\\\/\",\"name\":\"Baby - Nuage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/categorie\\\/baby-clothes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/categorie\\\/baby-clothes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Welcome\",\"item\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/home-01\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baby\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/\",\"name\":\"Nuage Concept Store\",\"description\":\"The Concept store for children\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/#organization\",\"name\":\"Nuage Concept Store\",\"url\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nuagelausanne.ch\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-LOGO_2022_SANS_ETOILE-e1643927377685.png\",\"contentUrl\":\"https:\\\/\\\/nuagelausanne.ch\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-LOGO_2022_SANS_ETOILE-e1643927377685.png\",\"width\":512,\"height\":512,\"caption\":\"Nuage Concept Store\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nuageconceptstore.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nuagelausanne\",\"https:\\\/\\\/www.instagram.com\\\/nuagelausanne\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baby - Nuage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nuageconceptstore.ch\/en\/categorie\/baby-clothes\/","og_locale":"en_US","og_type":"article","og_title":"Baby - Nuage","og_url":"https:\/\/www.nuageconceptstore.ch\/en\/categorie\/baby-clothes\/","og_site_name":"Nuage","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.nuageconceptstore.ch\/en\/categorie\/baby-clothes\/","url":"https:\/\/www.nuageconceptstore.ch\/en\/categorie\/baby-clothes\/","name":"Baby - Nuage","isPartOf":{"@id":"https:\/\/www.nuageconceptstore.ch\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.nuageconceptstore.ch\/en\/categorie\/baby-clothes\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nuageconceptstore.ch\/en\/categorie\/baby-clothes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Welcome","item":"https:\/\/www.nuageconceptstore.ch\/en\/home-01\/"},{"@type":"ListItem","position":2,"name":"Baby"}]},{"@type":"WebSite","@id":"https:\/\/www.nuageconceptstore.ch\/en\/#website","url":"https:\/\/www.nuageconceptstore.ch\/en\/","name":"Nuage Concept Store","description":"The Concept store for children","publisher":{"@id":"https:\/\/www.nuageconceptstore.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nuageconceptstore.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nuageconceptstore.ch\/en\/#organization","name":"Nuage Concept Store","url":"https:\/\/www.nuageconceptstore.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nuageconceptstore.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/nuagelausanne.ch\/wp-content\/uploads\/2022\/02\/cropped-LOGO_2022_SANS_ETOILE-e1643927377685.png","contentUrl":"https:\/\/nuagelausanne.ch\/wp-content\/uploads\/2022\/02\/cropped-LOGO_2022_SANS_ETOILE-e1643927377685.png","width":512,"height":512,"caption":"Nuage Concept Store"},"image":{"@id":"https:\/\/www.nuageconceptstore.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nuagelausanne","https:\/\/www.instagram.com\/nuagelausanne"]}]}},"_links":{"self":[{"href":"https:\/\/www.nuageconceptstore.ch\/en\/wp-json\/wp\/v2\/product_cat\/2222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nuageconceptstore.ch\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.nuageconceptstore.ch\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.nuageconceptstore.ch\/en\/wp-json\/wp\/v2\/product?product_cat=2222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}